{"id":12726,"date":"2023-05-19T14:53:11","date_gmt":"2023-05-19T17:53:11","guid":{"rendered":"https:\/\/www.cobapa.org.br\/portal\/?p=12726"},"modified":"2023-05-24T09:18:41","modified_gmt":"2023-05-24T12:18:41","slug":"proclamemos-a-verdade-aos-paraenses","status":"publish","type":"post","link":"https:\/\/www.cobapa.org.br\/portal\/proclamemos-a-verdade-aos-paraenses\/","title":{"rendered":"Proclamemos a verdade aos paraenses"},"content":{"rendered":"\n<p style=\"text-align: justify;\"><strong>Meus irm\u00e3os,<\/strong> falar sobre miss\u00f5es \u00e9 compartilhar algo que vem do cora\u00e7\u00e3o de Deus e toca os nossos cora\u00e7\u00f5es. Todos n\u00f3s cremos que Jo\u00e3o 3.16 \u00e9 verdade <strong>\u201cPorque Deus amou ao mundo de tal maneira que deu o seu Filho unig\u00eanito, para que todo o que nele cr\u00ea n\u00e3o pere\u00e7a, mas tenha a vida eterna\u201d. <\/strong>Esta \u00e9 a grande verdade do Evangelho, Jesus Cristo morreu por n\u00f3s na cruz do calv\u00e1rio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12731 size-full\" src=\"https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2023\/05\/topo-cartaz-ME2023.png\" alt=\"\" width=\"2504\" height=\"368\" srcset=\"https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2023\/05\/topo-cartaz-ME2023.png 2504w, https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2023\/05\/topo-cartaz-ME2023-300x44.png 300w, https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2023\/05\/topo-cartaz-ME2023-768x113.png 768w, https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2023\/05\/topo-cartaz-ME2023-2048x301.png 2048w, https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2023\/05\/topo-cartaz-ME2023-640x94.png 640w\" sizes=\"(max-width: 2504px) 100vw, 2504px\" \/><\/p>\n<p style=\"text-align: justify;\">Em cada campanha mission\u00e1ria, temos a oportunidade de anunciar esta poderosa mensagem de salva\u00e7\u00e3o. Por isso aguardamos o m\u00eas de miss\u00f5es estaduais com grande expectativa. Este ano vamos trabalhar com o tema <strong>Proclamemos a verdade aos paraenses<\/strong>, e a divisa: <strong>\u201cProcura apresentar-te a Deus aprovado, como obreiro que n\u00e3o tem de que se envergonhar, que maneja bem a palavra de verdade\u201d.<\/strong> (2\u00aa. Tm. 2.15). As igrejas e congrega\u00e7\u00f5es v\u00e3o receber todo o material, como todos os anos, o qual ser\u00e1 a base para o planejamento e elabora\u00e7\u00e3o das campanhas mission\u00e1rias nas igrejas. No sentido de ajudar as igrejas e congrega\u00e7\u00f5es, em tempos de miss\u00f5es, vamos compartilhar alguns pontos a seguir:<\/p>\n<ol style=\"text-align: justify;\">\n<li><strong>O mundo precisa ouvir a verdade de Deus. <\/strong>Esta campanha mission\u00e1ria visa o estado do Par\u00e1, mas, devemos ter em mente que o mundo inteiro precisa ouvir a verdade. E o que \u00e9 a verdade? Com base na B\u00edblia podemos dizer: 1) Verdade \u00e9 o que Deus diz em sua Palavra; 2) A pr\u00f3pria B\u00edblia \u00e9 chamada de a Palavra da Verdade; 3) Jesus Cristo, Filho de Deus, declarou-se como sendo a pr\u00f3pria verdade; 4) O Esp\u00edrito Santo, terceira pessoa da Trindade, \u00e9 reconhecido na B\u00edblia como o Esp\u00edrito da verdade; 5) O Evangelho \u00e9 ensinado como a verdade; 6) As cartas de Paulo ensinam que, os homens nada podem contra a verdade, mas a favor da verdade; 7) Jo\u00e3o, em seu evangelho, registrou que, a verdade, em Jesus, \u00e9 totalmente libertadora<strong>. \u201cConhecereis a verdade e a verdade vos libertar<\/strong>\u00e1\u201d. 8) As recomenda\u00e7\u00f5es \u00e9ticas na b\u00edblia instruem aos crentes que falem a verdade, vivam na verdade, e proclamem a verdade de que s\u00f3 existe um caminho para a salva\u00e7\u00e3o que \u00e9 Jesus. 9) <strong>Pessoas sem Deus est\u00e3o perdidas, desorientadas e infelizes, portanto, precisam ouvir a verdade de que Jesus Cristo pode mudar suas vidas para sempre e para melhor. <\/strong>10) Verdade para n\u00f3s crist\u00e3os \u00e9 a Palavra de Deus (Jo.17.17).<\/li>\n<li><strong>Os mission\u00e1rios precisam eliminar os paradoxos.<\/strong> Talvez nem haja consci\u00eancia da presen\u00e7a de paradoxo, mas as consequ\u00eancias est\u00e3o \u00e0 vista de todos. Perguntamos: Por que existem tantos crentes em d\u00favidas paralisantes a respeito de uma a\u00e7\u00e3o evangel\u00edstica? O paradoxo est\u00e1 no seguinte fato: de um lado a B\u00edblia mostra, em diversos textos, que a obra mission\u00e1ria no mundo est\u00e1 em fase de conclus\u00e3o; sendo que de outro lado temos as estat\u00edsticas globais sobre miss\u00f5es, mostrando que a obra estaria longe de ser conclu\u00edda, faltando quase tudo. Diante dessa aparente contradi\u00e7\u00e3o, n\u00e3o devemos vacilar pensando se estamos concluindo ou iniciando a miss\u00e3o no mundo. <strong>Mas, cabe-nos como mission\u00e1rios que somos, vencer os paradoxos mentais e, com determina\u00e7\u00e3o, permanecendo no prop\u00f3sito de Deus, cumprindo a nossa miss\u00e3o, procurando evangelizar todos os dias.<\/strong><\/li>\n<li><strong> As igrejas precisam combater a lentid\u00e3o mission\u00e1ria. <\/strong>Vivemos na \u00e9poca da velocidade, de avi\u00f5es supers\u00f4nicos, de carros velozes, comunica\u00e7\u00e3o instant\u00e2nea, transmiss\u00e3o em tempo real. A B\u00edblia nos ensina que a obra de Deus exige diligencia e rapidez. Quem j\u00e1 prestou a aten\u00e7\u00e3o na velocidade com que Jesus Cristo realizava as suas obras. Percebeu que durante toda a sua vida nunca esteve parado, o seu foco era miss\u00f5es todos os dias. Se voc\u00ea considerar somente os \u00faltimos tr\u00eas anos de Jesus, ele quase n\u00e3o parava a n\u00e3o ser para um pequeno descanso com os seus disc\u00edpulos. Quem j\u00e1 prestou a aten\u00e7\u00e3o na velocidade com que Paulo realizava as suas a\u00e7\u00f5es mission\u00e1rias, as suas viagens, as suas falas, pode perceber que o senso de urg\u00eancia faz parte da vida de um bom mission\u00e1rio. <strong>Devemos incentivar o nosso povo a imprimir mais velocidade em suas a\u00e7\u00f5es mission\u00e1rias<\/strong>. Miss\u00f5es est\u00e1 naquela lista de prioridades que n\u00e3o podemos deixar para amanh\u00e3, devemos faz\u00ea-la hoje.<\/li>\n<li><strong> Os l\u00edderes de miss\u00f5es precisam ter como foco a excel\u00eancia na obra mission\u00e1ria. <\/strong>Uma das verdades que a B\u00edblia ensina \u00e9 que <u>n\u00e3o devemos fazer a obra de Deus relaxadamente<\/u>! <strong>Mission\u00e1rios s\u00e3o pessoas que trabalham para Deus.<\/strong> <strong>Igrejas s\u00e3o ag\u00eancias mission\u00e1rias comprometidas com o Senhor<\/strong>. Quem tem <strong>compromisso com Deus deve procurar fazer o seu trabalho com excel\u00eancia<\/strong>. Deus espera o melhor de seus servos. Nada deve ser mais importante para um crente verdadeiro do que obedecer a Deus em termos de miss\u00f5es, fazendo a sua obra com excel\u00eancia. Os primeiros mission\u00e1rios da era crist\u00e3, <strong>aqueles que ariscaram tudo por miss\u00f5es<\/strong>, conhecidos como os Ap\u00f3stolos de Jesus Cristo, diziam: <strong>\u201c&#8230; Julgai v\u00f3s se \u00e9 justo, diante de Deus, ouvir-vos antes a v\u00f3s do que a Deus. Porque n\u00e3o podemos deixar de falar do que temos visto e ouvido. <\/strong>(Atos.4.19-20). Irm\u00e3os, miss\u00f5es \u00e9 a obra de excel\u00eancia do povo de Deus, ao realizarmos essa obra, devemos ter somente um sentimento: obedecer a Deus em amor e fazer o melhor poss\u00edvel para Ele. \u201c<strong>Tende em v\u00f3s o mesmo sentimento que houve tamb\u00e9m em Cristo Jesus<\/strong>\u201d. (Fp.2.5).<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">Pr. Ruy G. Ferreira,<\/p>\n<p style=\"text-align: justify;\">OPBB-PA 3640<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta \u00e9 a grande verdade do Evangelho, Jesus Cristo morreu por n\u00f3s na cruz do calv\u00e1rio.<\/p>\n","protected":false},"author":5,"featured_media":8713,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[278,14],"tags":[738,197,196,775],"_links":{"self":[{"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/posts\/12726"}],"collection":[{"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/comments?post=12726"}],"version-history":[{"count":3,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/posts\/12726\/revisions"}],"predecessor-version":[{"id":12733,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/posts\/12726\/revisions\/12733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/media\/8713"}],"wp:attachment":[{"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/media?parent=12726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/categories?post=12726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/tags?post=12726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}