{"id":6334,"date":"2016-09-16T16:27:08","date_gmt":"2016-09-16T19:27:08","guid":{"rendered":"http:\/\/www.cobapa.org.br\/portal\/?p=6334"},"modified":"2017-01-05T11:43:47","modified_gmt":"2017-01-05T14:43:47","slug":"rejubapa-total-2017","status":"publish","type":"post","link":"https:\/\/www.cobapa.org.br\/portal\/rejubapa-total-2017\/","title":{"rendered":"Rejubapa Total 2017"},"content":{"rendered":"<p style=\"text-align: justify;\">Em virtude de grandes eventos em 2017 a Cobapa realiza o <strong>REJUBAPA TOTAL<\/strong>. \u00c9 a jun\u00e7\u00e3o do <strong>Rejubapa<\/strong> e <strong>Rejubapa Teen<\/strong> que acontecer\u00e1 nos dias <strong>25 a 28 de Fevereiro<\/strong> em todas as Regionais.<\/p>\n<p style=\"text-align: justify;\">O <em><strong>Retiro da Juventude Batista da Cobapa<\/strong><\/em>\u00a0acontece em todas as Regionais com o\u00a0tema:\u00a0<span style=\"color: #ff0000;\"><strong>&#8220;A quem voc\u00ea anda imitando&#8221;<\/strong><span style=\"color: #000000;\">, divisa em 3Jo 1:11 que diz\u00a0<em><strong>&#8220;Amados, n\u00e3o imites o que \u00e9 mau, sen\u00e3o o que \u00e9 bom. Aquele que pratica o bem procede de Deus; aquele que pratica o mal jamais viu a Deus&#8221;<\/strong>. <\/em>O Retiro\u00a0<\/span><\/span>promover\u00e1 a integra\u00e7\u00e3o e crescimento dos jovens e adolescentes, destacando a\u00e7\u00f5es que contribuem com o fortalecimento da nossas juventude. Estimamos a participa\u00e7\u00e3o de 400 retirantes (150 jovens e 250 adolescentes &#8211; Acampamento de Castanhal), com uma programa\u00e7\u00e3o composta de palestras, oficinas e apresenta\u00e7\u00f5es art\u00edsticas diversas.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<table>\n<tbody>\n<tr>\n<td>\n<p style=\"text-align: center;\"><strong>INSCRI\u00c7\u00c3O PARA O\u00a0<span style=\"color: #0000ff;\">REJUBAPA TOTAL NA TOCANTINA<\/span><\/strong><\/p>\n<p style=\"text-align: center;\">Preletor oficial:<\/p>\n<p style=\"text-align: center;\"><strong>Pr. Edson Penha &#8211; Cobapa<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.cobapa.org.br\/boletos\/loja\/rejubapa-total\/rejubapa-total-2017-tocantina\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6363 size-full\" src=\"http:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/mini-banner-rejubapa2017-tocantina.jpg\" alt=\"mini-banner-rejubapa2017-tocantina\" width=\"300\" height=\"354\" srcset=\"https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/mini-banner-rejubapa2017-tocantina.jpg 300w, https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/mini-banner-rejubapa2017-tocantina-254x300.jpg 254w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<\/td>\n<td>\n<p style=\"text-align: center;\"><strong>INSCRI\u00c7\u00c3O PARA O <span style=\"color: #0000ff;\">REJUBAPA TOTAL EM CASTANHAL<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">Preletor oficial:<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\">Pr. Jorge Vinicius Machado &#8211; RJ<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.cobapa.org.br\/boletos\/loja\/rejubapa-total\/rejubapa-total-2017-castanhal\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6364 size-full\" src=\"http:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/mini-banner-rejubapa2017-CASTANHAL.jpg\" alt=\"mini-banner-rejubapa2017-castanhal\" width=\"300\" height=\"424\" srcset=\"https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/mini-banner-rejubapa2017-CASTANHAL.jpg 300w, https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/mini-banner-rejubapa2017-CASTANHAL-212x300.jpg 212w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table>\n<tbody>\n<tr>\n<td>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\">REJUBAPA TOTAL EM SANTAR\u00c9M<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12pt;\">Preletor oficial:\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 12pt;\">Pr.\u00a0M\u00e1rcio Rego<\/span><\/strong><\/p>\n<p><a href=\"http:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/cartaz-tocantina-2017.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-6854 size-full\" src=\"http:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/cartaz-tocantina-2017.jpeg\" alt=\"cartaz-tocantina-2017\" width=\"700\" height=\"400\" srcset=\"https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/cartaz-tocantina-2017.jpeg 700w, https:\/\/www.cobapa.org.br\/portal\/wp-content\/uploads\/2016\/09\/cartaz-tocantina-2017-300x171.jpeg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">\u00a0\u00a0<\/p>\n<p><span style=\"color: #000000; font-size: 14pt;\"><strong>1 &#8211; Objetivo<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Promover a coopera\u00e7\u00e3o da Juventude Batista das regi\u00f5es envolvidas;<\/span><\/li>\n<li><span style=\"color: #000000;\">Oportunizar a integra\u00e7\u00e3o jovem das igrejas Batistas;<\/span><\/li>\n<li><span style=\"color: #000000;\">Instrumentalizar nossos jovens para a\u00e7\u00f5es nas igrejas locais;<\/span><\/li>\n<li><span style=\"color: #000000;\">Viabilizar momentos de edifica\u00e7\u00e3o e crescimento espiritual.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000; font-size: 14pt;\"><strong>2 &#8211; Quem pode participar?<\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">Nesta edi\u00e7\u00e3o adolescentes e jovem podem participar. <strong>Idade entre 14 e 35 anos.<\/strong><\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000; font-size: 14pt;\"><strong>3 &#8211; O que levar?<\/strong><\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"color: #000000;\">B\u00edblia; material de uso e higiene pessoal; talheres (prato, garfo, faca, colhe); roupas e cal\u00e7ados leves para as atividades esportivas, lazer e de banho; toalha; rede (preferencial pois todos os alojamentos possuem armadores para rede) ou colchonete. Seja mordomo de seus objetos: note\/netbooks, tablets, iphones e equipamentos do g\u00eanero. A Coordenadoria se isenta caso ocorra perda, esquecimento ou roubo de qualquer equipamento mencionado acima.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #000000; font-size: 14pt;\"><strong>4 &#8211; Local: <\/strong><\/span><\/p>\n<ul>\n<li><span style=\"color: #000000;\">ACAMPAMENTO PARA\u00cdSO BATISTA EM CASTANHAL-PA &#8211; Av. Bar\u00e3o do Rio Branco S\/N.<\/span><\/li>\n<\/ul>\n<p><strong><span style=\"color: #000000; font-size: 14pt;\">5 &#8211; DETALHES IMPORTANTES PARA VOC\u00ca:<\/span><\/strong><\/p>\n<p style=\"padding-left: 60px; text-align: justify;\"><span style=\"color: #000000;\"><strong>5.1<\/strong> Se voc\u00ea desistir, haver\u00e1 DEVOLU\u00c7\u00c3O de 70% (setenta por cento) do valor da inscri\u00e7\u00e3o, mediante solicita\u00e7\u00e3o previa, por escrito, antes da realiza\u00e7\u00e3o do evento, ou seja, at\u00e9 17\/02\/2017. Os valores ser\u00e3o devolvidos somente na sede da COBAPA;<\/span><\/p>\n<p style=\"padding-left: 60px; text-align: justify;\"><span style=\"color: #000000;\"><strong>5.2<\/strong> A inscri\u00e7\u00e3o efetuada e que por qualquer motivo, deixar de ser gozada pelo retirante, poder\u00e1 ser transferida a outro, desde que comunicado \u00e0 Coordena\u00e7\u00e3o do Retiro para que promova as devidas altera\u00e7\u00f5es cadastrais;<\/span><\/p>\n<p style=\"padding-left: 60px; text-align: justify;\"><span style=\"color: #000000;\"><strong>5.3<\/strong> O investimento no Retiro \u00e9 de <strong>R$ 135,00<\/strong> podendo ser parcelado em <strong>3X de R$ 45,00<\/strong> (dezembro, janeiro\/17 e at\u00e9 dia 10\/02\/2017) no boleto banc\u00e1rio mediante preenchimento da <strong>Ficha de Inscri\u00e7\u00e3o<\/strong> online. Na <span style=\"color: #ff00ff;\"><strong>PROMO\u00c7\u00c3O R$ 120,00<\/strong> para pagamento a vista (via boleto ou diretamente no escrit\u00f3rio da Cobapa)<\/span>. O investimento cobrir\u00e1 despesas de CAF\u00c9 DA MANH\u00c3, ALMO\u00c7O, JANTAR, ESTADIA (local), MANUTEN\u00c7\u00c3O DO ACAMPAMENTO;<\/span><\/p>\n<hr \/>\n<p style=\"padding-left: 60px; text-align: justify;\"><a href=\"http:\/\/www.cobapa.org.br\/boletos\/loja\/rejubapa-total\/rejubapa-total-2017-castanhal\/\"><span style=\"color: #ff0000;\"><strong>Parcele agora em <em>3X de R$ 45,00<\/em> a sua inscri\u00e7\u00e3o para o Rejubapa Total em Castanhal clicando aqui e receba por e-mail os boletos para pagamento.<\/strong><\/span><\/a><\/p>\n<hr \/>\n<p style=\"padding-left: 60px; text-align: justify;\"><span style=\"color: #000000;\"><strong>5.4<\/strong> Voc\u00ea n\u00e3o poder\u00e1 deixar o acampamento sem pr\u00e9via autoriza\u00e7\u00e3o da <strong><em>Coordena\u00e7\u00e3o Geral do Rejubapa<\/em><\/strong>; <\/span><\/p>\n<p style=\"padding-left: 60px; text-align: justify;\"><span style=\"color: #000000;\"><strong>5.5<\/strong> A <em><strong>Coordena\u00e7\u00e3o Geral<\/strong><\/em> n\u00e3o se responsabilizar\u00e1 por objetos perdidos, esquecidos, desaparecidos, etc; <\/span><\/p>\n<p style=\"padding-left: 60px; text-align: justify;\"><span style=\"color: #000000;\"><strong>5.6<\/strong> Solicitamos a voc\u00ea retirante que colabore com a Coordena\u00e7\u00e3o, participando de todas as programa\u00e7\u00f5es e atividades propostas, afinal\u00a0<\/span><span style=\"color: #000000;\">TODAS foram pensadas para contribuir com sua vida espiritual; informamos que para os casos de desobedi\u00eancia \u00e0s orienta\u00e7\u00f5es e\/ou posturas n\u00e3o condizentes com a de um crist\u00e3o, a Coordena\u00e7\u00e3o Geral solicitar\u00e1 seu retorno ao local de origem, e sua Igreja ser\u00e1 notificada sobre suas atitudes.<\/span><\/p>\n<p style=\"padding-left: 60px; text-align: justify;\"><span style=\"color: #000000;\"><strong>5.7<\/strong>\u00a0Os port\u00f5es do\u00a0Acampamento ser\u00e3o <strong><em>abertos a partir das 16h do dia 25\/02 (s\u00e1bado) para receber os retirantes<\/em><\/strong>. Abertura do evento iniciando com o jantar as 18h e Culto come\u00e7ando as 19:30h.<\/span><\/p>\n<p style=\"text-align: center;\">\u00a0<\/p>\n<p><span style=\"font-size: 14pt; color: #ff0000;\"><strong>6 &#8211; Observe as seguintes considera\u00e7\u00f5es:<\/strong><\/span><\/p>\n<p style=\"padding-left: 60px; text-align: justify;\">\n<a  data-e-Disable-Page-Transition=\"true\" class=\"download-link download-button aligncenter\" title=\"\" href=\"https:\/\/www.cobapa.org.br\/portal\/download\/5081\/?tmstv=1788354108\" rel=\"nofollow\" id=\"download-link-5081\" data-redirect=\"false\" >\n\tDownload &ldquo;TERMO DE AUTORIZA\u00c7\u00c3O E CO-RESPONSABILIDADE&rdquo;\t<small>form-rejubapa2017-termo.pdf\t\t&ndash; Baixado 22200 vezes\t\t&ndash; 208,78 KB<\/small>\n<\/a>\n<\/p>\n<p style=\"padding-left: 60px; text-align: justify;\">6.1 O <strong>Termo de Autoriza\u00e7\u00e3o<\/strong> \u00e9 exclusivo para os adolescentes que dever\u00e1 ser assinado pelo respons\u00e1vel do adolescente e pelo pastor da igreja;<\/p>\n<p style=\"padding-left: 60px; text-align: justify;\">6.2 \u00c9 imprescind\u00edvel as assinaturas do respons\u00e1vel e pastor no Termo, sem elas n\u00e3o ser\u00e1 autorizada a entrada do menor nas depend\u00eancias do Acampamento Para\u00edso Batista (Castanhal e Santar\u00e9m), bem como nos demais\u00a0locais onde ser\u00e3o realizados os Retiros nas Regionais;<\/p>\n<p style=\"padding-left: 60px; text-align: justify;\">6.3 O Termo dever\u00e1 ser entregue no dia 25\/02 a equipe de inscri\u00e7\u00e3o que estar\u00e1 respons\u00e1vel pela confirma\u00e7\u00e3o das inscri\u00e7\u00f5es pagas e dados dos adolescentes, isso vale para os l\u00edderes dos adolescentes tamb\u00e9m;<\/p>\n<p style=\"padding-left: 60px; text-align: justify;\"><strong>6.4 S\u00f3 ser\u00e3o<\/strong> aceitas inscri\u00e7\u00f5es no local do Acampamento <strong>caso restem<\/strong> vagas a serem preenchidas dentro do limite (250 adolescentes), fora isso n\u00e3o ser\u00e3o aceitos nenhuma inscri\u00e7\u00e3o no local;<\/p>\n<p style=\"padding-left: 60px; text-align: justify;\">6.5 Ser\u00e1 comunicado oficialmente pelo Site e pelas M\u00eddias Sociais oficiais da Cobapa o limite alcan\u00e7ado para o <strong>Rejubapa Total\u00a02017<\/strong>;<\/p>\n<p style=\"padding-left: 60px; text-align: justify;\">\u00a0<\/p>\n<p style=\"padding-left: 60px; text-align: justify;\">6.6 A efetiva\u00e7\u00e3o das inscri\u00e7\u00f5es via site apenas garante em parte a pr\u00e9-inscri\u00e7\u00e3o, por\u00e9m somente o pagamento \u00e9 que efetivamente garante a participa\u00e7\u00e3o dos retirantes ao <strong>REJUBAPA TOTAL<\/strong>.<\/p>\n<hr \/>\n<p style=\"text-align: center;\"><strong><span style=\"font-size: 10pt;\">Somente para quem vai ao Rejubapa Total em Castanhal com sa\u00edda de Bel\u00e9m<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000; font-size: 18pt;\"><strong>ATEN\u00c7\u00c3O GALERA QUE VAI AO REJUBAPA TOTAL 2017.\u00a0Colocaremos dois \u00f4nibus para os 100 primeiros inscritos no valor de R$ 20,00 (ida e volta).\u00a0<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contatos:<\/strong> 3222-0307 (COBAPA) ou 99904-9947\u00a0(Wagner)<br \/>\n <strong>LOCAL de SA\u00cdDA:<\/strong>\u00a0ser\u00e1 informado dias antes do retiro.<br \/>\n <strong>DATA:<\/strong> 25 de fevereiro\u00a014h&#8230; rumo ao Acampamento Para\u00edso Batista<span class=\"text_exposed_show\"><br \/>\n <strong>OBS:<\/strong> os dois \u00f4nibus sair\u00e3o juntos&#8230;<\/span><\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #0000ff;\"><strong><span style=\"font-size: 14pt;\">Contatos e informa\u00e7\u00f5es:<\/span><\/strong><\/span><\/p>\n<p><span style=\"color: #000000; font-size: 10pt;\"><strong>Miss. Wagner Souza &#8211; 91-99904-9947 \/ 3222-0307<\/strong><\/span><\/p>\n<p><span style=\"font-size: 10pt;\"><strong>E-mail: rejubapa@cobapa.org.br\u00a0<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em virtude de grandes eventos em 2017 a Cobapa realiza o REJUBAPA TOTAL. \u00c9 a jun\u00e7\u00e3o do Rejubapa e Rejubapa Teen que acontecer\u00e1 nos dias 25 a 28 de Fevereiro em todas as Regionais. O Retiro da Juventude Batista da Cobapa\u00a0acontece em todas as Regionais com o\u00a0tema:\u00a0&#8220;A quem voc\u00ea anda imitando&#8221;, divisa em 3Jo 1:11 que diz\u00a0&#8220;Amados, n\u00e3o imites o [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":6363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[220,221],"tags":[],"_links":{"self":[{"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/posts\/6334"}],"collection":[{"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/comments?post=6334"}],"version-history":[{"count":28,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/posts\/6334\/revisions"}],"predecessor-version":[{"id":6855,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/posts\/6334\/revisions\/6855"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/media\/6363"}],"wp:attachment":[{"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/media?parent=6334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/categories?post=6334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cobapa.org.br\/portal\/wp-json\/wp\/v2\/tags?post=6334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}